{"id":4253,"date":"2026-05-12T18:05:29","date_gmt":"2026-05-12T21:05:29","guid":{"rendered":"https:\/\/soldadoadrianojose.com.br\/?p=4253"},"modified":"2026-05-12T18:09:31","modified_gmt":"2026-05-12T21:09:31","slug":"deputado-adriano-jose-reforca-valorizacao-da-policia-cientifica-com-projeto-que-institui-data-estadual-no-parana","status":"publish","type":"post","link":"https:\/\/soldadoadrianojose.com.br\/index.php\/2026\/05\/12\/deputado-adriano-jose-reforca-valorizacao-da-policia-cientifica-com-projeto-que-institui-data-estadual-no-parana\/","title":{"rendered":"Deputado Adriano Jos\u00e9 refor\u00e7a valoriza\u00e7\u00e3o da Pol\u00edcia Cient\u00edfica com projeto que institui data estadual no Paran\u00e1"},"content":{"rendered":"<p data-start=\"117\" data-end=\"670\">O deputado estadual <span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Adriano Jos\u00e9<\/span><\/span> \u00e9 um dos autores do projeto de lei que institui o Dia Estadual de Valoriza\u00e7\u00e3o dos Profissionais da Pol\u00edcia Cient\u00edfica, a ser celebrado em 4 de dezembro no Paran\u00e1. A proposta \u00e9 assinada em conjunto com outros deputados\u00a0e tem como objetivo reconhecer o trabalho t\u00e9cnico e essencial desempenhado pelos profissionais que atuam na produ\u00e7\u00e3o de provas periciais e no apoio \u00e0s investiga\u00e7\u00f5es criminais em todo o Estado.<\/p>\n<p data-start=\"672\" data-end=\"1089\">Presidente da Comiss\u00e3o de Seguran\u00e7a P\u00fablica da Assembleia Legislativa do Paran\u00e1, Adriano Jos\u00e9 destacou que a atua\u00e7\u00e3o da Pol\u00edcia Cient\u00edfica \u00e9 decisiva para o fortalecimento da justi\u00e7a e da seguran\u00e7a p\u00fablica. Segundo ele, os profissionais da \u00e1rea exercem uma fun\u00e7\u00e3o silenciosa, mas extremamente estrat\u00e9gica, contribuindo diretamente para a elucida\u00e7\u00e3o de crimes e para a garantia da verdade nos processos investigativos.<\/p>\n<p data-start=\"1091\" data-end=\"1518\">\u201cO trabalho da Pol\u00edcia Cient\u00edfica \u00e9 fundamental para a seguran\u00e7a da popula\u00e7\u00e3o e para a credibilidade das investiga\u00e7\u00f5es. S\u00e3o profissionais altamente capacitados, que atuam com responsabilidade, t\u00e9cnica e compromisso com a verdade. Essa homenagem \u00e9 uma forma de reconhecer a dedica\u00e7\u00e3o desses servidores que muitas vezes trabalham longe dos holofotes, mas t\u00eam papel decisivo na solu\u00e7\u00e3o de crimes\u201d, afirmou o deputado Adriano Jos\u00e9.<\/p>\n<p data-start=\"1520\" data-end=\"1955\">O projeto tamb\u00e9m busca ampliar o reconhecimento institucional e social dos profissionais que integram a Pol\u00edcia Cient\u00edfica, como peritos, m\u00e9dicos-legistas, papiloscopistas, odontolegistas e demais especialistas respons\u00e1veis pela an\u00e1lise t\u00e9cnica em ocorr\u00eancias criminais. A escolha da data de 4 de dezembro faz refer\u00eancia \u00e0 import\u00e2ncia hist\u00f3rica da atividade pericial e ao papel da ci\u00eancia na promo\u00e7\u00e3o da justi\u00e7a e da seguran\u00e7a p\u00fablica.<\/p>\n<p data-start=\"1957\" data-end=\"2400\" data-is-last-node=\"\" data-is-only-node=\"\">Para Adriano Jos\u00e9, iniciativas como essa fortalecem a valoriza\u00e7\u00e3o das for\u00e7as de seguran\u00e7a do Paran\u00e1 e demonstram respeito aos profissionais que dedicam suas vidas \u00e0 prote\u00e7\u00e3o da sociedade. \u201cDefender a seguran\u00e7a p\u00fablica tamb\u00e9m \u00e9 valorizar quem trabalha diariamente para garantir investiga\u00e7\u00f5es s\u00e9rias, transparentes e baseadas em evid\u00eancias. Nosso mandato seguir\u00e1 apoiando todas as categorias que contribuem para um Paran\u00e1 mais seguro\u201d, concluiu.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O deputado estadual Adriano Jos\u00e9 \u00e9 um dos autores do projeto de lei que institui o Dia Estadual de Valoriza\u00e7\u00e3o dos Profissionais da Pol\u00edcia Cient\u00edfica, a ser celebrado em 4 de dezembro no Paran\u00e1. A proposta \u00e9 assinada em conjunto com outros deputados\u00a0e tem como objetivo reconhecer o trabalho t\u00e9cnico e essencial desempenhado pelos profissionais [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":4256,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4253","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gabinete-sd"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Deputado Adriano Jos\u00e9 refor\u00e7a valoriza\u00e7\u00e3o da Pol\u00edcia Cient\u00edfica com projeto que institui data estadual no Paran\u00e1 - Deputado Adriano Jos\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/soldadoadrianojose.com.br\/index.php\/2026\/05\/12\/deputado-adriano-jose-reforca-valorizacao-da-policia-cientifica-com-projeto-que-institui-data-estadual-no-parana\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Deputado Adriano Jos\u00e9 refor\u00e7a valoriza\u00e7\u00e3o da Pol\u00edcia Cient\u00edfica com projeto que institui data estadual no Paran\u00e1 - Deputado Adriano Jos\u00e9\" \/>\n<meta property=\"og:description\" content=\"O deputado estadual Adriano Jos\u00e9 \u00e9 um dos autores do projeto de lei que institui o Dia Estadual de Valoriza\u00e7\u00e3o dos Profissionais da Pol\u00edcia Cient\u00edfica, a ser celebrado em 4 de dezembro no Paran\u00e1. A proposta \u00e9 assinada em conjunto com outros deputados\u00a0e tem como objetivo reconhecer o trabalho t\u00e9cnico e essencial desempenhado pelos profissionais [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/soldadoadrianojose.com.br\/index.php\/2026\/05\/12\/deputado-adriano-jose-reforca-valorizacao-da-policia-cientifica-com-projeto-que-institui-data-estadual-no-parana\/\" \/>\n<meta property=\"og:site_name\" content=\"Deputado Adriano Jos\u00e9\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-12T21:05:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T21:09:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/soldadoadrianojose.com.br\/wp-content\/uploads\/2026\/05\/Texto-do-seu-paragrafo-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Emanuellig admin2\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Emanuellig admin2\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/soldadoadrianojose.com.br\\\/index.php\\\/2026\\\/05\\\/12\\\/deputado-adriano-jose-reforca-valorizacao-da-policia-cientifica-com-projeto-que-institui-data-estadual-no-parana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/soldadoadrianojose.com.br\\\/index.php\\\/2026\\\/05\\\/12\\\/deputado-adriano-jose-reforca-valorizacao-da-policia-cientifica-com-projeto-que-institui-data-estadual-no-parana\\\/\"},\"author\":{\"name\":\"Emanuellig admin2\",\"@id\":\"https:\\\/\\\/soldadoadrianojose.com.br\\\/#\\\/schema\\\/person\\\/cd48425bd7edd36fa5917c88fbe1cec5\"},\"headline\":\"Deputado Adriano Jos\u00e9 refor\u00e7a valoriza\u00e7\u00e3o da Pol\u00edcia Cient\u00edfica com projeto que institui data estadual no Paran\u00e1\",\"datePublished\":\"2026-05-12T21:05:29+00:00\",\"dateModified\":\"2026-05-12T21:09:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/soldadoadrianojose.com.br\\\/index.php\\\/2026\\\/05\\\/12\\\/deputado-adriano-jose-reforca-valorizacao-da-policia-cientifica-com-projeto-que-institui-data-estadual-no-parana\\\/\"},\"wordCount\":383,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/soldadoadrianojose.com.br\\\/#\\\/schema\\\/person\\\/16f8e8defb7a4bd6c6082efcd1bdb6bb\"},\"image\":{\"@id\":\"https:\\\/\\\/soldadoadrianojose.com.br\\\/index.php\\\/2026\\\/05\\\/12\\\/deputado-adriano-jose-reforca-valorizacao-da-policia-cientifica-com-projeto-que-institui-data-estadual-no-parana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/soldadoadrianojose.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Texto-do-seu-paragrafo-1.jpg\",\"articleSection\":[\"GABINETE SD\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/soldadoadrianojose.com.br\\\/index.php\\\/2026\\\/05\\\/12\\\/deputado-adriano-jose-reforca-valorizacao-da-policia-cientifica-com-projeto-que-institui-data-estadual-no-parana\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/soldadoadrianojose.com.br\\\/index.php\\\/2026\\\/05\\\/12\\\/deputado-adriano-jose-reforca-valorizacao-da-policia-cientifica-com-projeto-que-institui-data-estadual-no-parana\\\/\",\"url\":\"https:\\\/\\\/soldadoadrianojose.com.br\\\/index.php\\\/2026\\\/05\\\/12\\\/deputado-adriano-jose-reforca-valorizacao-da-policia-cientifica-com-projeto-que-institui-data-estadual-no-parana\\\/\",\"name\":\"Deputado Adriano Jos\u00e9 refor\u00e7a valoriza\u00e7\u00e3o da Pol\u00edcia Cient\u00edfica com projeto que institui data estadual no Paran\u00e1 - Deputado Adriano Jos\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/soldadoadrianojose.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/soldadoadrianojose.com.br\\\/index.php\\\/2026\\\/05\\\/12\\\/deputado-adriano-jose-reforca-valorizacao-da-policia-cientifica-com-projeto-que-institui-data-estadual-no-parana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/soldadoadrianojose.com.br\\\/index.php\\\/2026\\\/05\\\/12\\\/deputado-adriano-jose-reforca-valorizacao-da-policia-cientifica-com-projeto-que-institui-data-estadual-no-parana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/soldadoadrianojose.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Texto-do-seu-paragrafo-1.jpg\",\"datePublished\":\"2026-05-12T21:05:29+00:00\",\"dateModified\":\"2026-05-12T21:09:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/soldadoadrianojose.com.br\\\/index.php\\\/2026\\\/05\\\/12\\\/deputado-adriano-jose-reforca-valorizacao-da-policia-cientifica-com-projeto-que-institui-data-estadual-no-parana\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/soldadoadrianojose.com.br\\\/index.php\\\/2026\\\/05\\\/12\\\/deputado-adriano-jose-reforca-valorizacao-da-policia-cientifica-com-projeto-que-institui-data-estadual-no-parana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/soldadoadrianojose.com.br\\\/index.php\\\/2026\\\/05\\\/12\\\/deputado-adriano-jose-reforca-valorizacao-da-policia-cientifica-com-projeto-que-institui-data-estadual-no-parana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/soldadoadrianojose.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Texto-do-seu-paragrafo-1.jpg\",\"contentUrl\":\"https:\\\/\\\/soldadoadrianojose.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Texto-do-seu-paragrafo-1.jpg\",\"width\":1080,\"height\":1350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/soldadoadrianojose.com.br\\\/index.php\\\/2026\\\/05\\\/12\\\/deputado-adriano-jose-reforca-valorizacao-da-policia-cientifica-com-projeto-que-institui-data-estadual-no-parana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/soldadoadrianojose.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Deputado Adriano Jos\u00e9 refor\u00e7a valoriza\u00e7\u00e3o da Pol\u00edcia Cient\u00edfica com projeto que institui data estadual no Paran\u00e1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/soldadoadrianojose.com.br\\\/#website\",\"url\":\"https:\\\/\\\/soldadoadrianojose.com.br\\\/\",\"name\":\"Deputado Adriano Jos\u00e9\",\"description\":\"Nosso trabalho \u00e9 pelas pessoas\",\"publisher\":{\"@id\":\"https:\\\/\\\/soldadoadrianojose.com.br\\\/#\\\/schema\\\/person\\\/16f8e8defb7a4bd6c6082efcd1bdb6bb\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/soldadoadrianojose.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/soldadoadrianojose.com.br\\\/#\\\/schema\\\/person\\\/16f8e8defb7a4bd6c6082efcd1bdb6bb\",\"name\":\"soldadoadrianojose\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/soldadoadrianojose.com.br\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/LOGO_CLEAR-5.png\",\"url\":\"https:\\\/\\\/soldadoadrianojose.com.br\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/LOGO_CLEAR-5.png\",\"contentUrl\":\"https:\\\/\\\/soldadoadrianojose.com.br\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/LOGO_CLEAR-5.png\",\"width\":3508,\"height\":998,\"caption\":\"soldadoadrianojose\"},\"logo\":{\"@id\":\"https:\\\/\\\/soldadoadrianojose.com.br\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/LOGO_CLEAR-5.png\"},\"sameAs\":[\"https:\\\/\\\/soldadoadrianojose.com.br\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/soldadoadrianojose.com.br\\\/#\\\/schema\\\/person\\\/cd48425bd7edd36fa5917c88fbe1cec5\",\"name\":\"Emanuellig admin2\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/soldadoadrianojose.com.br\\\/wp-content\\\/litespeed\\\/avatar\\\/235a59a115f40132a17fc909e61bc31d.jpg?ver=1778302705\",\"url\":\"https:\\\/\\\/soldadoadrianojose.com.br\\\/wp-content\\\/litespeed\\\/avatar\\\/235a59a115f40132a17fc909e61bc31d.jpg?ver=1778302705\",\"contentUrl\":\"https:\\\/\\\/soldadoadrianojose.com.br\\\/wp-content\\\/litespeed\\\/avatar\\\/235a59a115f40132a17fc909e61bc31d.jpg?ver=1778302705\",\"caption\":\"Emanuellig admin2\"},\"url\":\"https:\\\/\\\/soldadoadrianojose.com.br\\\/index.php\\\/author\\\/manu\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Deputado Adriano Jos\u00e9 refor\u00e7a valoriza\u00e7\u00e3o da Pol\u00edcia Cient\u00edfica com projeto que institui data estadual no Paran\u00e1 - Deputado Adriano Jos\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/soldadoadrianojose.com.br\/index.php\/2026\/05\/12\/deputado-adriano-jose-reforca-valorizacao-da-policia-cientifica-com-projeto-que-institui-data-estadual-no-parana\/","og_locale":"pt_BR","og_type":"article","og_title":"Deputado Adriano Jos\u00e9 refor\u00e7a valoriza\u00e7\u00e3o da Pol\u00edcia Cient\u00edfica com projeto que institui data estadual no Paran\u00e1 - Deputado Adriano Jos\u00e9","og_description":"O deputado estadual Adriano Jos\u00e9 \u00e9 um dos autores do projeto de lei que institui o Dia Estadual de Valoriza\u00e7\u00e3o dos Profissionais da Pol\u00edcia Cient\u00edfica, a ser celebrado em 4 de dezembro no Paran\u00e1. A proposta \u00e9 assinada em conjunto com outros deputados\u00a0e tem como objetivo reconhecer o trabalho t\u00e9cnico e essencial desempenhado pelos profissionais [&hellip;]","og_url":"https:\/\/soldadoadrianojose.com.br\/index.php\/2026\/05\/12\/deputado-adriano-jose-reforca-valorizacao-da-policia-cientifica-com-projeto-que-institui-data-estadual-no-parana\/","og_site_name":"Deputado Adriano Jos\u00e9","article_published_time":"2026-05-12T21:05:29+00:00","article_modified_time":"2026-05-12T21:09:31+00:00","og_image":[{"width":1080,"height":1350,"url":"https:\/\/soldadoadrianojose.com.br\/wp-content\/uploads\/2026\/05\/Texto-do-seu-paragrafo-1.jpg","type":"image\/jpeg"}],"author":"Emanuellig admin2","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Emanuellig admin2","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/soldadoadrianojose.com.br\/index.php\/2026\/05\/12\/deputado-adriano-jose-reforca-valorizacao-da-policia-cientifica-com-projeto-que-institui-data-estadual-no-parana\/#article","isPartOf":{"@id":"https:\/\/soldadoadrianojose.com.br\/index.php\/2026\/05\/12\/deputado-adriano-jose-reforca-valorizacao-da-policia-cientifica-com-projeto-que-institui-data-estadual-no-parana\/"},"author":{"name":"Emanuellig admin2","@id":"https:\/\/soldadoadrianojose.com.br\/#\/schema\/person\/cd48425bd7edd36fa5917c88fbe1cec5"},"headline":"Deputado Adriano Jos\u00e9 refor\u00e7a valoriza\u00e7\u00e3o da Pol\u00edcia Cient\u00edfica com projeto que institui data estadual no Paran\u00e1","datePublished":"2026-05-12T21:05:29+00:00","dateModified":"2026-05-12T21:09:31+00:00","mainEntityOfPage":{"@id":"https:\/\/soldadoadrianojose.com.br\/index.php\/2026\/05\/12\/deputado-adriano-jose-reforca-valorizacao-da-policia-cientifica-com-projeto-que-institui-data-estadual-no-parana\/"},"wordCount":383,"commentCount":0,"publisher":{"@id":"https:\/\/soldadoadrianojose.com.br\/#\/schema\/person\/16f8e8defb7a4bd6c6082efcd1bdb6bb"},"image":{"@id":"https:\/\/soldadoadrianojose.com.br\/index.php\/2026\/05\/12\/deputado-adriano-jose-reforca-valorizacao-da-policia-cientifica-com-projeto-que-institui-data-estadual-no-parana\/#primaryimage"},"thumbnailUrl":"https:\/\/soldadoadrianojose.com.br\/wp-content\/uploads\/2026\/05\/Texto-do-seu-paragrafo-1.jpg","articleSection":["GABINETE SD"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/soldadoadrianojose.com.br\/index.php\/2026\/05\/12\/deputado-adriano-jose-reforca-valorizacao-da-policia-cientifica-com-projeto-que-institui-data-estadual-no-parana\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/soldadoadrianojose.com.br\/index.php\/2026\/05\/12\/deputado-adriano-jose-reforca-valorizacao-da-policia-cientifica-com-projeto-que-institui-data-estadual-no-parana\/","url":"https:\/\/soldadoadrianojose.com.br\/index.php\/2026\/05\/12\/deputado-adriano-jose-reforca-valorizacao-da-policia-cientifica-com-projeto-que-institui-data-estadual-no-parana\/","name":"Deputado Adriano Jos\u00e9 refor\u00e7a valoriza\u00e7\u00e3o da Pol\u00edcia Cient\u00edfica com projeto que institui data estadual no Paran\u00e1 - Deputado Adriano Jos\u00e9","isPartOf":{"@id":"https:\/\/soldadoadrianojose.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/soldadoadrianojose.com.br\/index.php\/2026\/05\/12\/deputado-adriano-jose-reforca-valorizacao-da-policia-cientifica-com-projeto-que-institui-data-estadual-no-parana\/#primaryimage"},"image":{"@id":"https:\/\/soldadoadrianojose.com.br\/index.php\/2026\/05\/12\/deputado-adriano-jose-reforca-valorizacao-da-policia-cientifica-com-projeto-que-institui-data-estadual-no-parana\/#primaryimage"},"thumbnailUrl":"https:\/\/soldadoadrianojose.com.br\/wp-content\/uploads\/2026\/05\/Texto-do-seu-paragrafo-1.jpg","datePublished":"2026-05-12T21:05:29+00:00","dateModified":"2026-05-12T21:09:31+00:00","breadcrumb":{"@id":"https:\/\/soldadoadrianojose.com.br\/index.php\/2026\/05\/12\/deputado-adriano-jose-reforca-valorizacao-da-policia-cientifica-com-projeto-que-institui-data-estadual-no-parana\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/soldadoadrianojose.com.br\/index.php\/2026\/05\/12\/deputado-adriano-jose-reforca-valorizacao-da-policia-cientifica-com-projeto-que-institui-data-estadual-no-parana\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/soldadoadrianojose.com.br\/index.php\/2026\/05\/12\/deputado-adriano-jose-reforca-valorizacao-da-policia-cientifica-com-projeto-que-institui-data-estadual-no-parana\/#primaryimage","url":"https:\/\/soldadoadrianojose.com.br\/wp-content\/uploads\/2026\/05\/Texto-do-seu-paragrafo-1.jpg","contentUrl":"https:\/\/soldadoadrianojose.com.br\/wp-content\/uploads\/2026\/05\/Texto-do-seu-paragrafo-1.jpg","width":1080,"height":1350},{"@type":"BreadcrumbList","@id":"https:\/\/soldadoadrianojose.com.br\/index.php\/2026\/05\/12\/deputado-adriano-jose-reforca-valorizacao-da-policia-cientifica-com-projeto-que-institui-data-estadual-no-parana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/soldadoadrianojose.com.br\/"},{"@type":"ListItem","position":2,"name":"Deputado Adriano Jos\u00e9 refor\u00e7a valoriza\u00e7\u00e3o da Pol\u00edcia Cient\u00edfica com projeto que institui data estadual no Paran\u00e1"}]},{"@type":"WebSite","@id":"https:\/\/soldadoadrianojose.com.br\/#website","url":"https:\/\/soldadoadrianojose.com.br\/","name":"Deputado Adriano Jos\u00e9","description":"Nosso trabalho \u00e9 pelas pessoas","publisher":{"@id":"https:\/\/soldadoadrianojose.com.br\/#\/schema\/person\/16f8e8defb7a4bd6c6082efcd1bdb6bb"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/soldadoadrianojose.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":["Person","Organization"],"@id":"https:\/\/soldadoadrianojose.com.br\/#\/schema\/person\/16f8e8defb7a4bd6c6082efcd1bdb6bb","name":"soldadoadrianojose","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/soldadoadrianojose.com.br\/wp-content\/uploads\/2023\/02\/LOGO_CLEAR-5.png","url":"https:\/\/soldadoadrianojose.com.br\/wp-content\/uploads\/2023\/02\/LOGO_CLEAR-5.png","contentUrl":"https:\/\/soldadoadrianojose.com.br\/wp-content\/uploads\/2023\/02\/LOGO_CLEAR-5.png","width":3508,"height":998,"caption":"soldadoadrianojose"},"logo":{"@id":"https:\/\/soldadoadrianojose.com.br\/wp-content\/uploads\/2023\/02\/LOGO_CLEAR-5.png"},"sameAs":["https:\/\/soldadoadrianojose.com.br"]},{"@type":"Person","@id":"https:\/\/soldadoadrianojose.com.br\/#\/schema\/person\/cd48425bd7edd36fa5917c88fbe1cec5","name":"Emanuellig admin2","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/soldadoadrianojose.com.br\/wp-content\/litespeed\/avatar\/235a59a115f40132a17fc909e61bc31d.jpg?ver=1778302705","url":"https:\/\/soldadoadrianojose.com.br\/wp-content\/litespeed\/avatar\/235a59a115f40132a17fc909e61bc31d.jpg?ver=1778302705","contentUrl":"https:\/\/soldadoadrianojose.com.br\/wp-content\/litespeed\/avatar\/235a59a115f40132a17fc909e61bc31d.jpg?ver=1778302705","caption":"Emanuellig admin2"},"url":"https:\/\/soldadoadrianojose.com.br\/index.php\/author\/manu\/"}]}},"jetpack_featured_media_url":"https:\/\/soldadoadrianojose.com.br\/wp-content\/uploads\/2026\/05\/Texto-do-seu-paragrafo-1.jpg","_links":{"self":[{"href":"https:\/\/soldadoadrianojose.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soldadoadrianojose.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/soldadoadrianojose.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/soldadoadrianojose.com.br\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/soldadoadrianojose.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4253"}],"version-history":[{"count":1,"href":"https:\/\/soldadoadrianojose.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4253\/revisions"}],"predecessor-version":[{"id":4255,"href":"https:\/\/soldadoadrianojose.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4253\/revisions\/4255"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/soldadoadrianojose.com.br\/index.php\/wp-json\/wp\/v2\/media\/4256"}],"wp:attachment":[{"href":"https:\/\/soldadoadrianojose.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/soldadoadrianojose.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/soldadoadrianojose.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}